{"id":5113,"date":"2023-01-27T09:06:37","date_gmt":"2023-01-27T08:06:37","guid":{"rendered":"https:\/\/www.meccanoplastica-group.com\/?p=5113"},"modified":"2023-01-31T17:46:09","modified_gmt":"2023-01-31T16:46:09","slug":"meccanoplastica-alla-fiera-k-2022-2","status":"publish","type":"post","link":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/","title":{"rendered":"Meccanoplastica alla Fiera K 2022"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l92w8f7c-2366d2044b5177d024302ecea31334b6\">\n.avia-image-container.av-l92w8f7c-2366d2044b5177d024302ecea31334b6 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l92w8f7c-2366d2044b5177d024302ecea31334b6 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l92w8f7c-2366d2044b5177d024302ecea31334b6 av-styling- avia-align-center  avia-builder-el-0  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2235 avia-img-lazy-loading-not-2235 avia_image ' src=\"https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/K-Dusseldorf.jpeg\" alt='' title='K Dusseldorf'  height=\"108\" width=\"466\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/K-Dusseldorf.jpeg 466w, https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/K-Dusseldorf-300x70.jpeg 300w\" sizes=\"(max-width: 466px) 100vw, 466px\" \/><\/div><\/div><\/div>\n<section  class='av_textblock_section av-l8zrr587-7c869989cba136f485e133f40b8523dc '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>19 ottobre 2022 &#8211; K, Dusseldorf\u2028Il Gruppo Meccanoplastica si presenta alla prima fiera K \u2028post pandemia con un\u2019immagine completamente rinnovata.<br \/>\nUn volto nuovo, che non stravolge la tradizione, ma le offre freschezza e la proietta nel futuro, perch\u00e9 questo \u00e8 l\u2019obiettivo di Meccanoplastica per la fiera K e per il 2023: continuare a innovare le sue tre linee produttive &#8211; macchinari EBM, IBM, SBM &#8211; ma con la cura e la precisione proprie della filosofia dell\u2019artigianato made in Italy.<\/p>\n<p>La nuova comunicazione parte dal marchio: quattro barre spezzate lungo la diagonale che formano un quadrato bicolore.<br \/>\nGli angoli opposti alla diagonale arrotondati per richiamare le forme dei prodotti in plastica. \u2028Un lettering disegnato ad hoc con una O spezzata che segue la diagonale del marchio.<br \/>\nIl legame con il passato \u00e8 dato dai colori, mentre la novit\u00e0 \u00e8 la scelta di uno stile flat ed essenziale, che si adatta alla comunicazione sui device mobili, mezzo prevalente per la comunicazione via social, che Meccanoplastica rilancia con una revisione del canale youtube e della pagina Linkedin.<\/p>\n<p>\u201cLa nuova immagine che vi presentiamo quest\u2019oggi \u00e8 per noi un simbolo del dinamico cambiamento che stiamo portando in Azienda: innovare e migliorarsi, mantenendosi tuttavia fedeli alla propria \u201ceredit\u00e0 tradizionale\u201d, rimanendo persone appassionate che danno il proprio meglio al fine di costruire soluzioni tecnologiche di qualit\u00e0, che durino nel tempo\u201d.<\/p>\n<p>Il rinnovamento passa anche attraverso il sito, che acquisisce una nuova veste grafica e si arricchisce di una sezione dedicata alle applicazioni, per presentare la flessibilit\u00e0 delle macchine di Meccanoplastica nella creazione di oggetti in plastica.\u2028Il sito introduce anche un approfondimento sulla vision di Meccanoplastica e sulla sua attenzione nei confronti dell\u2019ambiente e della sostenibilit\u00e0, tema sempre pi\u00f9 centrale nell\u2019evoluzione del gruppo.<\/p>\n<p>Novit\u00e0 principale del 2022 in casa Meccanoplastica &#8211; a livello tecnologico &#8211; \u00e8 la presentazione della JET75-4, impianto full electric di Iniezione Soffiaggio a 4-stazioni, che si affianca al range tradizionale di impianti IBM a 3-stazioni della serie JET.<br \/>\nQuesto modello di macchina \u00e8 specificamente versatile per l\u2019utilizzo di resine quali le poliolefine (PE e PP) e resine pi\u00f9 dure quali PET \u2013 PETG e NYLON, di elevato utilizzo nel settore COSMETICO di prima fascia. Pertanto si rivolge soprattutto ai produttori di questo settore che devono realizzare il packaging per articoli quali mascara, lipgloss, etc..<\/p>\n<p>La comunicazione di Meccanoplastica Group:<br \/>\n&#8211; sito internet: www.meccanoplastica-group.com\/<br \/>\n&#8211; pagina Linkedin: www.linkedin.com\/company\/meccanoplastica\/<br \/>\n&#8211; profilo Youtube: www.youtube.com\/c\/Meccanoplasticagroup<\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l92wd5r7-3eb85588be8ef5a8a9dc0acdcf1a6fe1\">\n#top .hr.hr-invisible.av-l92wd5r7-3eb85588be8ef5a8a9dc0acdcf1a6fe1{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-l92wd5r7-3eb85588be8ef5a8a9dc0acdcf1a6fe1 hr-invisible  avia-builder-el-2  el_after_av_textblock  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":5164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,14],"tags":[],"class_list":["post-5113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiere","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meccanoplastica alla Fiera K 2022 - Meccanoplastica Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meccanoplastica alla Fiera K 2022 - Meccanoplastica Group\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Meccanoplastica Group\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T08:06:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T16:46:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/fiera-k-dusseldorf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"videoproduction\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"videoproduction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/\"},\"author\":{\"name\":\"videoproduction\",\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/#\\\/schema\\\/person\\\/3b2c9933f50da26da4cce0755e3464dc\"},\"headline\":\"Meccanoplastica alla Fiera K 2022\",\"datePublished\":\"2023-01-27T08:06:37+00:00\",\"dateModified\":\"2023-01-31T16:46:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/\"},\"wordCount\":762,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/fiera-k-dusseldorf.jpg\",\"articleSection\":[\"FIERE\",\"NEWS\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/\",\"url\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/\",\"name\":\"Meccanoplastica alla Fiera K 2022 - Meccanoplastica Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/fiera-k-dusseldorf.jpg\",\"datePublished\":\"2023-01-27T08:06:37+00:00\",\"dateModified\":\"2023-01-31T16:46:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/#\\\/schema\\\/person\\\/3b2c9933f50da26da4cce0755e3464dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/fiera-k-dusseldorf.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/fiera-k-dusseldorf.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/meccanoplastica-alla-fiera-k-2022-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/pagina-di-esempio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meccanoplastica alla Fiera K 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/\",\"name\":\"Meccanoplastica Group\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/#\\\/schema\\\/person\\\/3b2c9933f50da26da4cce0755e3464dc\",\"name\":\"videoproduction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfadf8e8bc8f223a0bdee0f3ffb67474bd858e6f9d9cc810351942b895b5f66?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfadf8e8bc8f223a0bdee0f3ffb67474bd858e6f9d9cc810351942b895b5f66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebfadf8e8bc8f223a0bdee0f3ffb67474bd858e6f9d9cc810351942b895b5f66?s=96&d=mm&r=g\",\"caption\":\"videoproduction\"},\"url\":\"https:\\\/\\\/www.meccanoplastica-group.com\\\/it\\\/author\\\/videoproduction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meccanoplastica alla Fiera K 2022 - Meccanoplastica Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/","og_locale":"it_IT","og_type":"article","og_title":"Meccanoplastica alla Fiera K 2022 - Meccanoplastica Group","og_url":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/","og_site_name":"Meccanoplastica Group","article_published_time":"2023-01-27T08:06:37+00:00","article_modified_time":"2023-01-31T16:46:09+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/fiera-k-dusseldorf.jpg","type":"image\/jpeg"}],"author":"videoproduction","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"videoproduction","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/#article","isPartOf":{"@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/"},"author":{"name":"videoproduction","@id":"https:\/\/www.meccanoplastica-group.com\/it\/#\/schema\/person\/3b2c9933f50da26da4cce0755e3464dc"},"headline":"Meccanoplastica alla Fiera K 2022","datePublished":"2023-01-27T08:06:37+00:00","dateModified":"2023-01-31T16:46:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/"},"wordCount":762,"commentCount":0,"image":{"@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/fiera-k-dusseldorf.jpg","articleSection":["FIERE","NEWS"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/","url":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/","name":"Meccanoplastica alla Fiera K 2022 - Meccanoplastica Group","isPartOf":{"@id":"https:\/\/www.meccanoplastica-group.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/#primaryimage"},"image":{"@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/fiera-k-dusseldorf.jpg","datePublished":"2023-01-27T08:06:37+00:00","dateModified":"2023-01-31T16:46:09+00:00","author":{"@id":"https:\/\/www.meccanoplastica-group.com\/it\/#\/schema\/person\/3b2c9933f50da26da4cce0755e3464dc"},"breadcrumb":{"@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/#primaryimage","url":"https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/fiera-k-dusseldorf.jpg","contentUrl":"https:\/\/www.meccanoplastica-group.com\/wp-content\/uploads\/2022\/09\/fiera-k-dusseldorf.jpg","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/www.meccanoplastica-group.com\/it\/meccanoplastica-alla-fiera-k-2022-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meccanoplastica-group.com\/it\/pagina-di-esempio\/"},{"@type":"ListItem","position":2,"name":"Meccanoplastica alla Fiera K 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.meccanoplastica-group.com\/it\/#website","url":"https:\/\/www.meccanoplastica-group.com\/it\/","name":"Meccanoplastica Group","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meccanoplastica-group.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.meccanoplastica-group.com\/it\/#\/schema\/person\/3b2c9933f50da26da4cce0755e3464dc","name":"videoproduction","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ebfadf8e8bc8f223a0bdee0f3ffb67474bd858e6f9d9cc810351942b895b5f66?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ebfadf8e8bc8f223a0bdee0f3ffb67474bd858e6f9d9cc810351942b895b5f66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebfadf8e8bc8f223a0bdee0f3ffb67474bd858e6f9d9cc810351942b895b5f66?s=96&d=mm&r=g","caption":"videoproduction"},"url":"https:\/\/www.meccanoplastica-group.com\/it\/author\/videoproduction\/"}]}},"_links":{"self":[{"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/posts\/5113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/comments?post=5113"}],"version-history":[{"count":0,"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/posts\/5113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/media\/5164"}],"wp:attachment":[{"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/media?parent=5113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/categories?post=5113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.meccanoplastica-group.com\/it\/wp-json\/wp\/v2\/tags?post=5113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}